{"id":282,"count":1,"description":"","link":"https:\/\/carrillolaw.com\/en\/tag\/acuerdo-ministerial-no-209-2023\/","name":"Acuerdo Ministerial No. 209-2023","slug":"acuerdo-ministerial-no-209-2023","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/carrillolaw.com\/en\/tag\/acuerdo-ministerial-no-209-2023\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/282\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carrillolaw.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/tag\\\/acuerdo-ministerial-no-209-2023\\\/#listItem\",\"name\":\"Acuerdo Ministerial No. 209-2023\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/tag\\\/acuerdo-ministerial-no-209-2023\\\/#listItem\",\"position\":2,\"name\":\"Acuerdo Ministerial No. 209-2023\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/282\\\/#collectionpage\",\"url\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/282\\\/\",\"name\":\"Acuerdo Ministerial No. 209-2023 - Carrillo & Asociados\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/282\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/#organization\",\"name\":\"Carrillo & Asociados\",\"description\":\"Inspirados por justicia, integridad y estado de derecho\",\"url\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/\",\"telephone\":\"+50224215700\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carrillolaw.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-header.svg\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/282\\\/#organizationLogo\",\"width\":240,\"height\":50},\"image\":{\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/282\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/carrillo-&-asociados\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/\",\"name\":\"Carrillo & Asociados\",\"description\":\"Inspirados por justicia, integridad y estado de derecho\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/carrillolaw.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script type=\"text\/javascript\">\n\t\t\t(function(c,l,a,r,i,t,y){\n\t\t\tc[a]=c[a]||function(){(c[a].q=c[a].q||[]).push(arguments)};t=l.createElement(r);t.async=1;\n\t\t\tt.src=\"https:\/\/www.clarity.ms\/tag\/\"+i+\"?ref=aioseo\";y=l.getElementsByTagName(r)[0];y.parentNode.insertBefore(t,y);\n\t\t})(window, document, \"clarity\", \"script\", \"hgcw16nufh\");\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Acuerdo Ministerial No. 209-2023 - Carrillo & Asociados","description":"","canonical_url":"https:\/\/carrillolaw.com\/en\/tag\/acuerdo-ministerial-no-209-2023\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carrillolaw.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/carrillolaw.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/carrillolaw.com\/en\/tag\/acuerdo-ministerial-no-209-2023\/#listItem","name":"Acuerdo Ministerial No. 209-2023"}},{"@type":"ListItem","@id":"https:\/\/carrillolaw.com\/en\/tag\/acuerdo-ministerial-no-209-2023\/#listItem","position":2,"name":"Acuerdo Ministerial No. 209-2023","previousItem":{"@type":"ListItem","@id":"https:\/\/carrillolaw.com\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282\/#collectionpage","url":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282\/","name":"Acuerdo Ministerial No. 209-2023 - Carrillo & Asociados","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/carrillolaw.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/carrillolaw.com\/en\/#organization","name":"Carrillo & Asociados","description":"Inspirados por justicia, integridad y estado de derecho","url":"https:\/\/carrillolaw.com\/en\/","telephone":"+50224215700","logo":{"@type":"ImageObject","url":"https:\/\/carrillolaw.com\/wp-content\/uploads\/2022\/04\/logo-header.svg","@id":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282\/#organizationLogo","width":240,"height":50},"image":{"@id":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/company\/carrillo-&-asociados"]},{"@type":"WebSite","@id":"https:\/\/carrillolaw.com\/en\/#website","url":"https:\/\/carrillolaw.com\/en\/","name":"Carrillo & Asociados","description":"Inspirados por justicia, integridad y estado de derecho","inLanguage":"en-US","publisher":{"@id":"https:\/\/carrillolaw.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/carrillolaw.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAcuerdo Ministerial No. 209-2023\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carrillolaw.com\/en"},{"label":"Acuerdo Ministerial No. 209-2023","link":"https:\/\/carrillolaw.com\/en\/tag\/acuerdo-ministerial-no-209-2023\/"}],"_links":{"self":[{"href":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/carrillolaw.com\/en\/wp-json\/wp\/v2\/posts?tags=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}